{"id":20,"date":"2022-07-27T17:36:25","date_gmt":"2022-07-27T15:36:25","guid":{"rendered":"https:\/\/conslondra.esteri.it\/?page_id=20"},"modified":"2022-10-11T16:06:56","modified_gmt":"2022-10-11T14:06:56","slug":"news","status":"publish","type":"page","link":"https:\/\/conslondra.esteri.it\/it\/news\/","title":{"rendered":"Notizie"},"content":{"rendered":"        <div class=\"row\">\n\t\t\t<!-- Ricerca sedi post -->\n\t\t\t<div class=\"col-12 mt-4\">\n\t\t\t  <div class=\"callout callout-highlight note ricerca-esteri p-4\">\n                    <div class=\"callout-title\">\n                        <svg class=\"icon\">\n                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-search\"><\/use>\n                        <\/svg>Inserisci i parametri di ricerca                    <\/div>\n                    <form id=\"searchFormPost\" name=\"form-search-post\" class=\"form-row align-items-center\" action=\"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20\/\" method=\"GET\"> \n                        <!-- <div class=\"form-group pt-5\"> -->\n                            <!-- <input type=\"hidden\" id=\"lang\" name=\"lang\" value=\"\"> --> <!-- <\/div> -->\n\n                        <div class=\"it-datepicker-wrapper\">\n                            <div class=\"row\">\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-init\">Dal<\/label>\n                                    <input class=\"form-control\" name=\"date-init\" id=\"date-init\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\"lang=\"en-EN\">  \n                                <\/div>\n                                <div class=\"form-group col-md-6\">\n                                    <label class=\"active\" for=\"date-end\">Al<\/label>\n                                    <input class=\"form-control\" name=\"date-end\" id=\"date-end\" type=\"date\" placeholder=\"gg\/mm\/aaaa\" value=\"\">\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"form-group col-md-12 mt-3\">\n                            <label for=\"searchText\">Campo ricerca libera<\/label>\n                            <input type=\"text\" name=\"searchText\" class=\"form-control\" id=\"searchText\" value=\"\">\n                        <\/div>\n                        <div class=\"form-group col-md-4 offset-md-8 text-end\">\n                            <a href=\"https:\/\/conslondra.esteri.it\/it\/news\/\" title=\"Form reset\" id=\"resetImput\" class=\"btn btn-outline-primary btn-xs\">Reset<\/a>\n                            <button type=\"submit\" class=\"btn btn-primary btn-xs\">Mostra risultati<\/button>\n                        <\/div>\n                    <\/form>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n                    \n            <div class=\"row\">\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 28 Agosto 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/08\/chiusura-del-consolato-generale-lunedi-31-agosto-summer-bank-holiday\/\" title=\"Chiusura del Consolato Generale luned\u00ec 31 agosto (Summer Bank Holiday)\">Chiusura del Consolato Generale luned\u00ec 31 agosto (Summer Bank Holiday)<\/a><\/h5>\n                            <p class=\"card-text\">Si ricorda all\u2019utenza che il Consolato Generale d\u2019Italia a Londra\u00a0rester\u00e0 chiuso nella giornata di luned\u00ec 31 agosto. In caso di comprovata emergenza, si prega di contattare il numero di emergenza presente nella home page.<\/p>\n                                <a title=\"Chiusura del Consolato Generale luned\u00ec 31 agosto (Summer Bank Holiday)\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/08\/chiusura-del-consolato-generale-lunedi-31-agosto-summer-bank-holiday\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 23 Luglio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/07\/elezioni-comites-2026\/\" title=\"Elezioni dei Comites 2026\">Elezioni dei Comites 2026<\/a><\/h5>\n                            <p class=\"card-text\">&nbsp; Elezioni dei Comites 2026: inizio campagna informativa Predisposizione e presentazione delle liste elettorali. Sottoscrizione e autentiche delle firme. Modalit\u00e0 per la richiesta di iscrizione nell&#8217;elenco elettorale\u00a0<\/p>\n                                <a title=\"Elezioni dei Comites 2026\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/07\/elezioni-comites-2026\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 18 Giugno 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/06\/canale-neo-mamme\/\" title=\"Canale &#8220;Neo Mamme&#8221;\">Canale &#8220;Neo Mamme&#8221;<\/a><\/h5>\n                            <p class=\"card-text\">Il Consolato Generale informa che dal 20 luglio 2026 \u00e8\u00a0 istituito il canale \u201cNeo Mamme\u201d, dedicato alle cittadine italiane , iscritte all\u2019AIRE nella circoscrizione di questo Consolato. Tale canale consentir\u00e0 loro di recarsi presso il Consolato Generale entro sei mesi dalla nascita del figlio, senza appuntamento, dal luned\u00ec al venerd\u00ec dalle 09.00 alle 12.00, per [&hellip;]<\/p>\n                                <a title=\"Canale &#8220;Neo Mamme&#8221;\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/06\/canale-neo-mamme\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 16 Giugno 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/06\/18876\/\" title=\"Possibilit\u00e0 di richiesta della carta d\u2019identit\u00e0 elettronica presso i Comuni italiani anche per i cittadini iscritti all\u2019AIRE\">Possibilit\u00e0 di richiesta della carta d\u2019identit\u00e0 elettronica presso i Comuni italiani anche per i cittadini iscritti all\u2019AIRE<\/a><\/h5>\n                            <p class=\"card-text\">A seguito dell\u2019entrata in vigore della legge n.11 del 19 gennaio 2026 anche i cittadini italiani iscritti all\u2019Anagrafe degli Italiani Residenti all\u2019Estero (AIRE),\u00a0a decorrere dal 1\u00b0 giugno 2026, potranno presentare domanda di rilascio della\u00a0Carta d\u2019Identit\u00e0 Elettronica\u00a0(CIE)\u00a0presso qualsiasi Comune\u00a0italiano, e non esclusivamente tramite l\u2019Ufficio consolare. I residenti all&#8217;estero iscritti all&#8217;AIRE potranno fissare un appuntamento tramite la [&hellip;]<\/p>\n                                <a title=\"Possibilit\u00e0 di richiesta della carta d\u2019identit\u00e0 elettronica presso i Comuni italiani anche per i cittadini iscritti all\u2019AIRE\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/06\/18876\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 20 Maggio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/05\/27-e-28-maggio-sospensione-dei-servizi-consolari-e-chiusura-del-consolato-al-pubblico\/\" title=\"27 e 28 maggio: sospensione dei servizi consolari e chiusura del Consolato al pubblico\">27 e 28 maggio: sospensione dei servizi consolari e chiusura del Consolato al pubblico<\/a><\/h5>\n                            <p class=\"card-text\">Si informano i gentili connazionali che nei giorni di\u00a0mercoled\u00ec 27\u00a0e\u00a0gioved\u00ec 28 maggio,\u00a0l\u2019erogazione di\u00a0tutti i servizi\u00a0consolari\u00a0(compresa l\u2019emissione di ETD \u2013 Emergency Travel Document)\u00a0sar\u00e0 temporaneamente sospesa,\u00a0per consentire un\u2019attivit\u00e0 straordinaria di manutenzione degli applicativi informatici della sede. L\u2019erogazione dei servizi consolari riprender\u00e0 regolarmente nei giorni successivi, secondo il consueto orario di apertura al pubblico. Ci scusiamo per il [&hellip;]<\/p>\n                                <a title=\"27 e 28 maggio: sospensione dei servizi consolari e chiusura del Consolato al pubblico\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/05\/27-e-28-maggio-sospensione-dei-servizi-consolari-e-chiusura-del-consolato-al-pubblico\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 1 Maggio 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/05\/chiusura-del-consolato-generale-lunedi-4-maggio-early-may-bank-holiday\/\" title=\"Chiusura del Consolato Generale luned\u00ec 4 maggio (Early May Bank Holiday)\">Chiusura del Consolato Generale luned\u00ec 4 maggio (Early May Bank Holiday)<\/a><\/h5>\n                            <p class=\"card-text\">Si ricorda all\u2019utenza che il Consolato Generale d\u2019Italia a Londra\u00a0rester\u00e0 chiuso nella giornata di luned\u00ec 4 maggio. In caso di comprovata emergenza, si prega di contattare il numero di emergenza presente nella home page.<\/p>\n                                <a title=\"Chiusura del Consolato Generale luned\u00ec 4 maggio (Early May Bank Holiday)\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/05\/chiusura-del-consolato-generale-lunedi-4-maggio-early-may-bank-holiday\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 2 Aprile 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/04\/chiusura-del-consolato-per-le-festivita-pasquali\/\" title=\"Chiusura del Consolato per le festivit\u00e0 di Pasqua\">Chiusura del Consolato per le festivit\u00e0 di Pasqua<\/a><\/h5>\n                            <p class=\"card-text\">Si ricorda all\u2019utenza che il Consolato Generale d\u2019Italia a Londra\u00a0rester\u00e0 chiuso nelle seguenti date: Venerd\u00ec Santo 3 aprile (Good Friday), Sabato 4 aprile, Domenica di Pasqua 5 aprile, Luned\u00ec dell\u2019Angelo 6 aprile In caso di comprovata emergenza, si prega di contattare il numero di emergenza Numeri di emergenza \u2013 Consolato Generale d&#8217;Italia Londra Le attivit\u00e0 [&hellip;]<\/p>\n                                <a title=\"Chiusura del Consolato per le festivit\u00e0 di Pasqua\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/04\/chiusura-del-consolato-per-le-festivita-pasquali\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 31 Marzo 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/03\/partita-di-calcio-tra-crystal-palace-e-fiorentina-in-programma-il-9-aprile-p-v-presso-lo-stadio-selhurst-park-informazioni-utili\/\" title=\"Partita di calcio tra Crystal Palace e Fiorentina in programma il 9 aprile p.v. presso lo stadio &#8221; Selhurst Park &#8220;. Informazioni utili.\">Partita di calcio tra Crystal Palace e Fiorentina in programma il 9 aprile p.v. presso lo stadio &#8221; Selhurst Park &#8220;. Informazioni utili.<\/a><\/h5>\n                            <p class=\"card-text\">In occasione della partita di calcio di UEFA Conference League tra Crystal Palace e Fiorentina in programma il 9 aprile p.v. presso lo stadio &#8221; Selhurst Park &#8220;, sono disponibili informazioni utili a beneficio dei tifosi italiani che intendano seguire il match allo stadio.<\/p>\n                                <a title=\"Partita di calcio tra Crystal Palace e Fiorentina in programma il 9 aprile p.v. presso lo stadio &#8221; Selhurst Park &#8220;. Informazioni utili.\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/03\/partita-di-calcio-tra-crystal-palace-e-fiorentina-in-programma-il-9-aprile-p-v-presso-lo-stadio-selhurst-park-informazioni-utili\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 20 Marzo 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/03\/digitalizzazione-del-sistema-migratorio-uk-ultimi-aggiornamenti\/\" title=\"Digitalizzazione del sistema migratorio UK: ultimi aggiornamenti.\">Digitalizzazione del sistema migratorio UK: ultimi aggiornamenti.<\/a><\/h5>\n                            <p class=\"card-text\">eVisa nel Regno Unito In qualit\u00e0 di cittadino italiano residente nel Regno Unito, potresti aver precedentemente utilizzato un permesso di soggiorno biometrico (BRP) o una carta di soggiorno biometrica (BRC) per dimostrare il tuo status di immigrazione. Il Governo del Regno Unito sta sviluppando un sistema di immigrazione digitale, che prevede la sostituzione dei documenti [&hellip;]<\/p>\n                                <a title=\"Digitalizzazione del sistema migratorio UK: ultimi aggiornamenti.\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/03\/digitalizzazione-del-sistema-migratorio-uk-ultimi-aggiornamenti\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n                            <div class=\"col-12 mt-3\">\n                <!--start card-->\n                <div class=\"card-wrapper card-space\">\n                    <div class=\"card card-bg card-big border-bottom-card\">\n                        <div class=\"card-body \">\n                                                        <div class=\"category-top\">\n                                                                                                            <span class=\"\">\n                                        <svg class=\"icon icon-secondary\">\n                                            <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-calendar\"><\/use>\n                                        <\/svg> 6 Marzo 2026                                    <\/span>\n                                                                    <\/div>\n                            <h5 class=\"card-title big-heading text-uppercase\"><a class=\"text-body text-decoration-none\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/03\/referendum-costituzionale-2026-rilascio-dei-duplicati\/\" title=\"Referendum Costituzionale 2026: rilascio dei duplicati\">Referendum Costituzionale 2026: rilascio dei duplicati<\/a><\/h5>\n                            <p class=\"card-text\">Si informa che A PARTIRE DA DOMENICA 8 MARZO 2026 gli elettori che non hanno ricevuto il plico elettorale per il voto per corrispondenza in occasione del referendum costituzionale del 22 e 23 marzo al proprio indirizzo di residenza potranno richiederne un DUPLICATO a questo Consolato. La richiesta di duplicato potr\u00e0 essere presentata, a partire [&hellip;]<\/p>\n                                <a title=\"Referendum Costituzionale 2026: rilascio dei duplicati\" class=\"read-more\" href=\"https:\/\/conslondra.esteri.it\/it\/news\/dal_consolato\/2026\/03\/referendum-costituzionale-2026-rilascio-dei-duplicati\/\">\n                                    <span class=\"text\">Leggi di pi\u00f9<\/span>\n                                    <svg class=\"icon\">\n                                    <use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-arrow-right\"><\/use>\n                                    <\/svg>\n                                <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n                <!--end card-->\n                <\/div><!-- col-12 .mt-3-->\n            \n            <div class=\"col-md-12 mt-4 pb-4\">\n                <nav class=\"navigation col-md-12\" aria-label=\"Navigation\">\n                    <h2 class=\"screen-reader-text visually-hidden\">Paginazione<\/h2>\n                    <div class=\"nav-links\">\n                    <span aria-current=\"page\" class=\"page-numbers current\">1<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20\/?pag=2\">2<\/a>\n<a class=\"page-numbers\" href=\"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20\/?pag=3\">3<\/a>\n<span class=\"page-numbers dots\">&hellip;<\/span>\n<a class=\"page-numbers\" href=\"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20\/?pag=78\">78<\/a>\n<a class=\"next page-numbers\" href=\"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20\/?pag=2\"><svg class=\"icon icon-primary\"><use xlink:href=\"https:\/\/conslondra.esteri.it\/wp-content\/themes\/sedi\/assets\/svg\/sprites.svg#it-chevron-right\"><\/use><\/svg>\n                                    <span class=\"visually-hidden\">Pagina successiva<\/span><\/a>                    <\/div>\n                <\/nav>\n            <\/div>   <!--.col-md-12 -->\n              <\/div><!--.row -->\n              \n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-20","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=20"}],"version-history":[{"count":0,"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/pages\/20\/revisions"}],"wp:attachment":[{"href":"https:\/\/conslondra.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=20"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}